{"id":2,"date":"2020-02-05T07:19:22","date_gmt":"2020-02-05T06:19:22","guid":{"rendered":"https:\/\/viacordis-akademie.de\/elernen\/?page_id=2"},"modified":"2024-12-31T12:00:28","modified_gmt":"2024-12-31T11:00:28","slug":"lernplattform","status":"publish","type":"page","link":"https:\/\/viacordis-akademie.de\/elernen\/","title":{"rendered":"Lernplattform"},"content":{"rendered":"<style>.kb-row-layout-id2_cdcfe3-4c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_cdcfe3-4c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_cdcfe3-4c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:140px;padding-right:24px;padding-bottom:140px;padding-left:24px;grid-template-columns:minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(40% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id2_cdcfe3-4c{background-image:url('https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2024\/01\/schreiben802.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2_cdcfe3-4c > .kt-row-layout-overlay{opacity:0.70;background:linear-gradient(90deg,rgb(0,0,0) 0%,rgba(204,204,153,0.5) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id2_cdcfe3-4c > .kt-row-column-wrap{padding-top:100px;padding-right:40px;padding-bottom:100px;padding-left:40px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2_cdcfe3-4c > .kt-row-column-wrap{padding-top:80px;padding-right:20px;padding-bottom:80px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_cdcfe3-4c alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_703c2b-64 > .kt-inside-inner-col,.kadence-column2_703c2b-64 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_703c2b-64 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_703c2b-64 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_703c2b-64 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_703c2b-64 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_703c2b-64{position:relative;}@media all and (max-width: 1024px){.kadence-column2_703c2b-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_703c2b-64 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_703c2b-64\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd, .wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd[data-kb-block=\"kb-adv-heading2_967b2f-bd\"]{font-size:24px;font-style:normal;text-shadow:1px 1px 2px #000000;}.wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd[data-kb-block=\"kb-adv-heading2_967b2f-bd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd[data-kb-block=\"kb-adv-heading2_967b2f-bd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd, .wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd[data-kb-block=\"kb-adv-heading2_967b2f-bd\"]{text-shadow:1px 1px 2px #000000;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd, .wp-block-kadence-advancedheading.kt-adv-heading2_967b2f-bd[data-kb-block=\"kb-adv-heading2_967b2f-bd\"]{text-shadow:1px 1px 2px #000000;font-size:22px;}}<\/style>\n<h6 class=\"kt-adv-heading2_967b2f-bd wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading2_967b2f-bd\">Deine Welt ver\u00e4ndert sich, ver\u00e4ndere dich mit.<\/h6>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae, .wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae[data-kb-block=\"kb-adv-heading2_188fc2-ae\"]{font-size:var(--global-kb-font-size-xl, 3rem);font-style:normal;text-shadow:1px 1px 2px #000000;}.wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae[data-kb-block=\"kb-adv-heading2_188fc2-ae\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae[data-kb-block=\"kb-adv-heading2_188fc2-ae\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae, .wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae[data-kb-block=\"kb-adv-heading2_188fc2-ae\"]{text-shadow:1px 1px 2px #000000;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae, .wp-block-kadence-advancedheading.kt-adv-heading2_188fc2-ae[data-kb-block=\"kb-adv-heading2_188fc2-ae\"]{text-shadow:1px 1px 2px #000000;line-height:1.2;}}<\/style>\n<h2 class=\"kt-adv-heading2_188fc2-ae wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading2_188fc2-ae\">Lerne f\u00fcr deine Zukunft, wann immer, wo immer und so lange du willst.<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column2_3a2507-41 > .kt-inside-inner-col{display:flex;}.kadence-column2_3a2507-41 > .kt-inside-inner-col,.kadence-column2_3a2507-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_3a2507-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2_3a2507-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2_3a2507-41{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2_3a2507-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_3a2507-41{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2_3a2507-41{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2_3a2507-41{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2_3a2507-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_3a2507-41\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns2_c7f397-dd{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns2_c7f397-dd .kt-button{font-weight:normal;font-style:normal;}.kt-btns2_c7f397-dd .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns2_c7f397-dd .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns2_c7f397-dd\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2_a0ab73-09.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn2_a0ab73-09 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/\"><span class=\"kt-btn-inner-text\">Alle Kurse<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2_a0f07d-90.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn2_a0f07d-90 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/viacordis-akademie.de\/elernen\/anmeldung-fuer-kursteilnehmer\/\"><span class=\"kt-btn-inner-text\">Registrieren<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_4f3026-04 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_4f3026-04 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_4f3026-04 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:60px;padding-bottom:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_4f3026-04 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_4f3026-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_4f3026-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_4f3026-04 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_9e36a3-01 > .kt-inside-inner-col,.kadence-column2_9e36a3-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_9e36a3-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_9e36a3-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_9e36a3-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_9e36a3-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_9e36a3-01{position:relative;}@media all and (max-width: 1024px){.kadence-column2_9e36a3-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_9e36a3-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_9e36a3-01\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6, .wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6[data-kb-block=\"kb-adv-heading2_5c5c16-b6\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6[data-kb-block=\"kb-adv-heading2_5c5c16-b6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_5c5c16-b6[data-kb-block=\"kb-adv-heading2_5c5c16-b6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2_5c5c16-b6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2_5c5c16-b6\">Neue Kurse<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Vor kurzem online gestellt, sehe dir gleich die neuesten E-Kurse an.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_3d0a99-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_3d0a99-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_3d0a99-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_3d0a99-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_3d0a99-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_3d0a99-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_3d0a99-20 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_c1357f-26 > .kt-inside-inner-col,.kadence-column2_c1357f-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_c1357f-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_c1357f-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_c1357f-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_c1357f-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_c1357f-26{position:relative;}@media all and (max-width: 1024px){.kadence-column2_c1357f-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_c1357f-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_c1357f-26\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop2_bbf0b0-75 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_bbf0b0-75 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;background-color:rgba(255,255,255,0);overflow:hidden;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{text-align:left;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;background-color:#ffffff;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#a1a1a1;font-size:14px;line-height:14px;letter-spacing:-0.4px;}.kt-post-loop2_bbf0b0-75 .entry-content{background-color:#fff;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_bbf0b0-75 .kt-blocks-post-footer{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_bbf0b0-75 .entry-content:after{height:0px;}.kt-post-loop2_bbf0b0-75 .entry-content .kt-blocks-post-readmore{background-color:#ffffff;border-color:var(--global-palette1, #3182CE);color:var(--global-palette1, #3182CE);border-width:1px;border-radius:5px;padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:16px;line-height:18px;}.kt-post-loop2_bbf0b0-75 .entry-content .kt-blocks-post-readmore:hover{color:var(--global-palette5, #4A5568);border-color:var(--global-palette5, #4A5568);background-color:var(--global-palette9, #ffffff);}.kt-post-loop2_bbf0b0-75 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_bbf0b0-75.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}@media all and (max-width: 1024px){.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop2_bbf0b0-75 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop2_bbf0b0-75 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-outlinedark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\"><li class=\"kt-post-slider-item post-356 courses type-courses status-publish has-post-thumbnail hentry course-category-wohlbefinden course-tag-anwendung course-tag-eigentherapie course-tag-gesundsein course-tag-gluecklichsein course-tag-lebensqualitaet course-tag-therapie\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\" aria-label=\"Aktiv gesund Programm\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Aktiv Gesund\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\">Aktiv gesund Programm<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Mit dem Aktiv gesund Programm bekommst du verst\u00e4ndliche Wege und M\u00f6glichkeiten zu Eigentherapie um emotionale, k\u00f6rperliche und energetische St\u00f6rungen zu beseitigen.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\">Mehr zeigen&#8230;<span class=\"screen-reader-text\"> Aktiv gesund Programm<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1635 courses type-courses status-publish has-post-thumbnail hentry course-category-innergetic course-tag-gesundheitsstoerungen course-tag-informationsfelder course-tag-innergetic course-tag-mksmm\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-12\/\" aria-label=\"Mein K\u00f6rper spricht mit mir, Teil 12\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-600x336.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-920x516.jpg 920w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-460x258.jpg 460w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm112.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-12\/\">Mein K\u00f6rper spricht mit mir, Teil 12<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Weiterbildung in der Innergetic. Themen-Hintergr\u00fcnde in diesem Kurs sind: Verdauung, Waschzwang, Wirbels\u00e4ule, Z\u00e4hne, Zahnfleisch und Zw\u00f6lffingerdarm.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-12\/\">Mehr zeigen&#8230;<span class=\"screen-reader-text\"> Mein K\u00f6rper spricht mit mir, Teil 12<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1567 courses type-courses status-publish has-post-thumbnail hentry course-category-innergetic course-tag-gesundheitsstoerungen course-tag-informationsfelder course-tag-innergetic course-tag-mksmm\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-11\/\" aria-label=\"Mein K\u00f6rper spricht mit mir, Teil 11\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"MKSMM T11\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-600x336.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-920x516.jpg 920w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111-460x258.jpg 460w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/03\/mKsmm111.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-11\/\">Mein K\u00f6rper spricht mit mir, Teil 11<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Weiterbildung in der Innergetic. Themen-Hintergr\u00fcnde in diesem Kurs sind:  Schilddr\u00fcse, Schlaflosigkeit, Schlaganfall, Schlafst\u00f6rungen, Schultern und Stress.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-11\/\">Mehr zeigen&#8230;<span class=\"screen-reader-text\"> Mein K\u00f6rper spricht mit mir, Teil 11<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1439 courses type-courses status-publish has-post-thumbnail hentry course-category-innergetic course-tag-gesundheitsstoerungen course-tag-informationsfelder course-tag-innergetic course-tag-mksmm\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-10\/\" aria-label=\"Mein K\u00f6rper spricht mit mir, Teil 10\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-600x336.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-920x516.jpg 920w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-460x258.jpg 460w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/mKsmm110.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-10\/\">Mein K\u00f6rper spricht mit mir, Teil 10<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Weiterbildung in der Innergetic. Themen-Hintergr\u00fcnde in diesem Kurs sind: Ohren, Ordnungsliebe, Parkinson, Penis, Prostata, Rheuma und Scheide.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/mein-koerper-spricht-mit-mir-teil-10\/\">Mehr zeigen&#8230;<span class=\"screen-reader-text\"> Mein K\u00f6rper spricht mit mir, Teil 10<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1369 courses type-courses status-publish has-post-thumbnail hentry course-category-wohlbefinden course-tag-natur course-tag-selbstheilung\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/baden-im-wald-selbst-praktizieren\/\" aria-label=\"Baden im Wald selbst praktizieren\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Baden im Wald\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-600x336.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-920x516.jpg 920w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100-460x258.jpg 460w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/02\/alice-100.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/baden-im-wald-selbst-praktizieren\/\">Baden im Wald selbst praktizieren<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Baden im Wald bringt deine f\u00fcnf Sinne in Schwung, st\u00e4rkt dein Immunsystem, bringt K\u00f6rper und Geist in Einklang und steigert deine Lebensqualit\u00e4t. Mit der richtigen Eigentherapie l\u00e4sst sich dein Alltag ku\u0308nftig entspannter und ges\u00fcnder meistern.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/baden-im-wald-selbst-praktizieren\/\">Mehr zeigen&#8230;<span class=\"screen-reader-text\"> Baden im Wald selbst praktizieren<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_fe99bf-22 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_fe99bf-22 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_fe99bf-22 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:60px;padding-bottom:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_fe99bf-22 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_fe99bf-22 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_fe99bf-22 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_fe99bf-22 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_369e88-66 > .kt-inside-inner-col,.kadence-column2_369e88-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_369e88-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_369e88-66 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_369e88-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_369e88-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_369e88-66{position:relative;}@media all and (max-width: 1024px){.kadence-column2_369e88-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_369e88-66 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_369e88-66\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9, .wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9[data-kb-block=\"kb-adv-heading2_6da2c7-a9\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9[data-kb-block=\"kb-adv-heading2_6da2c7-a9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_6da2c7-a9[data-kb-block=\"kb-adv-heading2_6da2c7-a9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2_6da2c7-a9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2_6da2c7-a9\">Unsere Empfehlung<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">E-Lernen f\u00fcr deine Zukunft, f\u00fcr deine Berufung, deine Leidenschaft oder um etwas Neues zu lernen.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_505370-1f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_505370-1f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_505370-1f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:30px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_505370-1f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_505370-1f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_505370-1f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_505370-1f alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_663cee-18 > .kt-inside-inner-col,.kadence-column2_663cee-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_663cee-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_663cee-18 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_663cee-18 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_663cee-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_663cee-18{position:relative;}@media all and (max-width: 1024px){.kadence-column2_663cee-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_663cee-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_663cee-18\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop2_deb305-49 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_deb305-49 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;overflow:hidden;}.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#a1a1a1;font-size:14px;line-height:14px;letter-spacing:-0.4px;}.kt-post-loop2_deb305-49 .entry-content{padding-top:10px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_deb305-49 .kt-blocks-post-footer{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:15px;padding-bottom:5px;padding-left:15px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_deb305-49 .entry-content:after{height:0px;}.kt-post-loop2_deb305-49 .entry-content .kt-blocks-post-readmore{background-color:#ffffff;border-color:var(--global-palette1, #3182CE);color:var(--global-palette1, #3182CE);border-width:1px;border-radius:5px;padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:16px;line-height:18px;}.kt-post-loop2_deb305-49 .entry-content .kt-blocks-post-readmore:hover{color:var(--global-palette5, #4A5568);border-color:var(--global-palette5, #4A5568);background-color:var(--global-palette9, #ffffff);}.kt-post-loop2_deb305-49 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_deb305-49.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}@media all and (max-width: 1024px){.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop2_deb305-49 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop2_deb305-49 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-outlinedark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\"><li class=\"kt-post-slider-item post-382 courses type-courses status-publish has-post-thumbnail hentry course-category-lebensstil course-category-wohlbefinden course-tag-innergetic course-tag-lebensqualitaet course-tag-motivation course-tag-transformation\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/sei-das-was-du-bist\/\" aria-label=\"Sei das was du bist\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Sei das was du bist - Der E-Kurs\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/frau111.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/sei-das-was-du-bist\/\">Sei das was du bist<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Schritt f\u00fcr Schritt Anleitung zu Transformation und zu positiven Ver\u00e4nderungen in deinem Leben. Denn nichts wird sich \u00e4ndern, wenn Du es nicht \u00e4nderst!<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/sei-das-was-du-bist\/\">Mehr zeigen &#8230;<span class=\"screen-reader-text\"> Sei das was du bist<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-356 courses type-courses status-publish has-post-thumbnail hentry course-category-wohlbefinden course-tag-anwendung course-tag-eigentherapie course-tag-gesundsein course-tag-gluecklichsein course-tag-lebensqualitaet course-tag-therapie\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\" aria-label=\"Aktiv gesund Programm\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Aktiv Gesund\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/aktivgesund1011.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\">Aktiv gesund Programm<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Mit dem Aktiv gesund Programm bekommst du verst\u00e4ndliche Wege und M\u00f6glichkeiten zu Eigentherapie um emotionale, k\u00f6rperliche und energetische St\u00f6rungen zu beseitigen.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/aktiv-gesund-programm\/\">Mehr zeigen &#8230;<span class=\"screen-reader-text\"> Aktiv gesund Programm<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-315 courses type-courses status-publish has-post-thumbnail hentry course-category-lebensstil course-category-wohlbefinden course-tag-achtsamkeit course-tag-gesundsein course-tag-gluecklichsein course-tag-lebensqualitaet course-tag-spiritualitaet\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-Top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:56.15234375%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/meditation-starter-kurs\/\" aria-label=\"Meditation Starter Kurs\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Meditation\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-720x404.jpg 720w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-360x202.jpg 360w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/meditation-100-1.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/meditation-starter-kurs\/\">Meditation Starter Kurs<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Der Meditation Starter Kurs ist der perfekte Einstig in die Welt der Meditation. Inklusive der 5 Minuten Meditation f\u00fcr Energie und Kraft.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/courses\/meditation-starter-kurs\/\">Mehr zeigen &#8230;<span class=\"screen-reader-text\"> Meditation Starter Kurs<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_08d909-8f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_08d909-8f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_08d909-8f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:60px;padding-bottom:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_08d909-8f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_08d909-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_08d909-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_08d909-8f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2_180e91-e3 > .kt-inside-inner-col,.kadence-column2_180e91-e3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_180e91-e3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_180e91-e3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_180e91-e3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_180e91-e3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_180e91-e3{position:relative;}@media all and (max-width: 1024px){.kadence-column2_180e91-e3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_180e91-e3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_180e91-e3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa, .wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa[data-kb-block=\"kb-adv-heading2_460cd6-fa\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa[data-kb-block=\"kb-adv-heading2_460cd6-fa\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_460cd6-fa[data-kb-block=\"kb-adv-heading2_460cd6-fa\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2_460cd6-fa wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2_460cd6-fa\">Warum ViaCordis Akademie w\u00e4hlen?<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_fd12f5-da > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_fd12f5-da > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_fd12f5-da > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:30px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_fd12f5-da > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_fd12f5-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_fd12f5-da > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_fd12f5-da alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_59be26-e9 > .kt-inside-inner-col,.kadence-column2_59be26-e9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_59be26-e9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_59be26-e9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_59be26-e9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_59be26-e9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_59be26-e9{position:relative;}@media all and (max-width: 1024px){.kadence-column2_59be26-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_59be26-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_59be26-e9\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id2_1f62d8-fb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id2_1f62d8-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_1f62d8-fb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2_664198-e0 > .kt-inside-inner-col,.kadence-column2_664198-e0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_664198-e0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_664198-e0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_664198-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_664198-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_664198-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column2_664198-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_664198-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_664198-e0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#fff;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box2_c52ee9-18.wp-block-kadence-infobox{max-width:100%;}.kt-info-box2_c52ee9-18 .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box2_c52ee9-18 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:512px;height:0px;max-width:100%;}.kt-info-box2_c52ee9-18 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box2_c52ee9-18 .kt-info-svg-icon-flip, .kt-info-box2_c52ee9-18 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box2_c52ee9-18 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_c52ee9-18 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box2_c52ee9-18 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box2_c52ee9-18\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/dsgvo71.png\" alt=\"\" width=\"512\" height=\"512\" class=\"kt-info-box-image wp-image-1229\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/dsgvo71.png 512w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/dsgvo71-300x300.png 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/dsgvo71-150x150.png 150w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/dsgvo71-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Standort Deutschland<\/h4><p class=\"kt-blocks-info-box-text\">Die ViaCordis Akademie ist ein deutsches Unternehmen, wir verwenden deutsche Server nach deutscher DSGVO und unsere Kurse sind f\u00fcr den deutschsprachigen Raum.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2_46651a-c0 > .kt-inside-inner-col,.kadence-column2_46651a-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_46651a-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_46651a-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_46651a-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_46651a-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_46651a-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column2_46651a-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_46651a-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_46651a-c0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#fff;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box2_43b1d4-f6.wp-block-kadence-infobox{max-width:100%;}.kt-info-box2_43b1d4-f6 .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box2_43b1d4-f6 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:512px;height:0px;max-width:100%;}.kt-info-box2_43b1d4-f6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box2_43b1d4-f6 .kt-info-svg-icon-flip, .kt-info-box2_43b1d4-f6 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box2_43b1d4-f6 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_43b1d4-f6 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box2_43b1d4-f6 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box2_43b1d4-f6\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/qualitaet71.png\" alt=\"\" width=\"512\" height=\"512\" class=\"kt-info-box-image wp-image-1231\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/qualitaet71.png 512w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/qualitaet71-300x300.png 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/qualitaet71-150x150.png 150w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/qualitaet71-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Gepr\u00fcfte Qualit\u00e4t<\/h4><p class=\"kt-blocks-info-box-text\">Auf ViaCordis Akademie findest du Klasse statt Masse. Nur von uns gewissenhaft gepr\u00fcfte und ausgew\u00e4hlte Dozenten sowie Online-Kurse finden den Weg auf die Lernplattform.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2_990cfb-9c > .kt-inside-inner-col,.kadence-column2_990cfb-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_990cfb-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_990cfb-9c > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_990cfb-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_990cfb-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_990cfb-9c{position:relative;}@media all and (max-width: 1024px){.kadence-column2_990cfb-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_990cfb-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_990cfb-9c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#fff;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap:hover{background:#f2f2f2;}.kt-info-box2_2fd0ac-07.wp-block-kadence-infobox{max-width:100%;}.kt-info-box2_2fd0ac-07 .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box2_2fd0ac-07 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:512px;height:0px;max-width:100%;}.kt-info-box2_2fd0ac-07 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box2_2fd0ac-07 .kt-info-svg-icon-flip, .kt-info-box2_2fd0ac-07 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:15px;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box2_2fd0ac-07 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_2fd0ac-07 .kt-infobox-textcontent .kt-blocks-info-box-text{color:#555555;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box2_2fd0ac-07 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box2_2fd0ac-07\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\" href=\"https:\/\/viacordis-akademie.de\/elernen\/faq\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/chat71.png\" alt=\"\" width=\"512\" height=\"512\" class=\"kt-info-box-image wp-image-1232\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/chat71.png 512w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/chat71-300x300.png 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/chat71-150x150.png 150w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2021\/01\/chat71-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Top Unterst\u00fctzung<\/h4><p class=\"kt-blocks-info-box-text\">Wir sind gerne f\u00fcr dich da, unser VCA Support-Team unterst\u00fctzt dich bei deinen Fragen und wenn es mal schnell gehen soll, findest du hier digitale Hilfe zu vielen Themen.<\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_a10abf-4a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_a10abf-4a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_a10abf-4a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:60px;padding-bottom:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_a10abf-4a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_a10abf-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_a10abf-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_a10abf-4a alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_bf5dd0-fb > .kt-inside-inner-col,.kadence-column2_bf5dd0-fb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_bf5dd0-fb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_bf5dd0-fb > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_bf5dd0-fb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_bf5dd0-fb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_bf5dd0-fb{position:relative;}@media all and (max-width: 1024px){.kadence-column2_bf5dd0-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_bf5dd0-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_bf5dd0-fb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2, .wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2[data-kb-block=\"kb-adv-heading2_96157b-c2\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2[data-kb-block=\"kb-adv-heading2_96157b-c2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2_96157b-c2[data-kb-block=\"kb-adv-heading2_96157b-c2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2_96157b-c2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2_96157b-c2\">Neueste Beitr\u00e4ge<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Interessante Themen aus der Welt des E-Lernens. Mehr im <a href=\"https:\/\/viacordis-akademie.de\/elernen\/blog\/\">Blog hier<\/a>&#8230;<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2_229c11-1d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2_229c11-1d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2_229c11-1d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:30px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2_229c11-1d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2_229c11-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2_229c11-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2_229c11-1d alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2_ec6760-9f > .kt-inside-inner-col,.kadence-column2_ec6760-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2_ec6760-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2_ec6760-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column2_ec6760-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2_ec6760-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2_ec6760-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column2_ec6760-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2_ec6760-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2_ec6760-9f\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop2_f37d16-c7 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_f37d16-c7 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;background-color:rgba(255,255,255,0);overflow:hidden;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#a1a1a1;}.kt-post-loop2_f37d16-c7 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:18px;}.kt-post-loop2_f37d16-c7 .kt-blocks-post-footer{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_f37d16-c7 .entry-content:after{height:0px;}.kt-post-loop2_f37d16-c7 .entry-content .kt-blocks-post-readmore{background-color:#ffffff;border-color:var(--global-palette1, #3182CE);color:var(--global-palette1, #3182CE);border-width:1px;border-radius:5px;padding-top:5px;padding-right:10px;padding-bottom:5px;padding-left:10px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:16px;line-height:18px;}.kt-post-loop2_f37d16-c7 .entry-content .kt-blocks-post-readmore:hover{color:var(--global-palette5, #4A5568);border-color:var(--global-palette5, #4A5568);background-color:var(--global-palette9, #ffffff);}.kt-post-loop2_f37d16-c7 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop2_f37d16-c7.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}@media all and (max-width: 1024px){.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}@media all and (max-width: 767px){.kt-post-loop2_f37d16-c7 .kt-blocks-post-grid-item{border-top-color:currentColor;border-top-style:solid;border-right-color:currentColor;border-right-style:solid;border-bottom-color:currentColor;border-bottom-style:solid;border-left-color:currentColor;border-left-style:solid;}}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop2_f37d16-c7 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-none kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"false\" data-slider-arrows=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"2\" data-columns-ss=\"1\"><li class=\"kt-post-slider-item post-1249 post type-post status-publish format-standard has-post-thumbnail hentry category-glossar\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-50\" style=\"padding-bottom:50%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/content-management-system\/\" aria-label=\"Content Management System\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-600x336.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-720x404.jpg 720w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-360x202.jpg 360w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-920x516.jpg 920w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101-460x258.jpg 460w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/wp101.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/content-management-system\/\">Content Management System<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Was ist ein Content Management System (CMS)? Ein Content Management System, ins deutsche \u00fcbersetzt: Inhalt-Verwaltungs-System, ist eine Software zur Erstellung,&#8230;<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/content-management-system\/\">Weiterlesen &#8230;<span class=\"screen-reader-text\"> Content Management System<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-374 post type-post status-publish format-standard has-post-thumbnail hentry category-glossar\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-50\" style=\"padding-bottom:50%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/learning-management-system\/\" aria-label=\"Learning Management System\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-960x538.jpg 960w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-480x269.jpg 480w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-720x404.jpg 720w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-360x202.jpg 360w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/dozent101.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/learning-management-system\/\">Learning Management System<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Was ist ein Learning Management System (LMS), ins deutsche \u00fcbersetzt: Was ist ein Lern-Verwaltungs-System? Hier erf\u00e4hrst du, einfach und kompakt,&#8230;<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/learning-management-system\/\">Weiterlesen &#8230;<span class=\"screen-reader-text\"> Learning Management System<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-glossar tag-streaming tag-video\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-50\" style=\"padding-bottom:50%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/viacordis-akademie.de\/elernen\/video-on-demand\/\" aria-label=\"Was ist Video on Demand\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-1024x575.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Video on Demand\" srcset=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-1024x575.jpg 1024w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-300x168.jpg 300w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-768x431.jpg 768w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-600x337.jpg 600w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-840x472.jpg 840w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-420x236.jpg 420w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-960x538.jpg 960w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-480x269.jpg 480w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-720x404.jpg 720w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100-360x202.jpg 360w, https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/video100.jpg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h3 class=\"entry-title\"><a href=\"https:\/\/viacordis-akademie.de\/elernen\/video-on-demand\/\">Was ist Video on Demand<\/a><\/h3><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\">Was ist Video on Demand? Von der VCA-Redaktion einfach erkl\u00e4rt: Video on Demand ist ein Video auf Abruf, d. h&#8230;.<div class=\"kt-blocks-post-readmore-wrap\"><a class=\"kt-blocks-post-readmore\" href=\"https:\/\/viacordis-akademie.de\/elernen\/video-on-demand\/\">Weiterlesen &#8230;<span class=\"screen-reader-text\"> Was ist Video on Demand<\/span><\/a><\/div><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Deine Welt ver\u00e4ndert sich, ver\u00e4ndere dich mit. Lerne f\u00fcr deine Zukunft, wann immer, wo immer und so lange du willst. Neue Kurse Vor kurzem online gestellt, sehe dir gleich die neuesten E-Kurse an. Unsere Empfehlung E-Lernen f\u00fcr deine Zukunft, f\u00fcr deine Berufung, deine Leidenschaft oder um etwas Neues zu lernen. Warum ViaCordis Akademie w\u00e4hlen? Neueste&#8230;<\/p>\n","protected":false},"author":1,"featured_media":66,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"bottom","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lernplattform mit Herz und Verstand - ViaCordis Akademie<\/title>\n<meta name=\"description\" content=\"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viacordis-akademie.de\/elernen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lernplattform mit Herz und Verstand - ViaCordis Akademie\" \/>\n<meta property=\"og:description\" content=\"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viacordis-akademie.de\/elernen\/\" \/>\n<meta property=\"og:site_name\" content=\"ViaCordis Akademie eLernen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-31T11:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1069\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\",\"url\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\",\"name\":\"Lernplattform mit Herz und Verstand - ViaCordis Akademie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/02\\\/vca101.jpg\",\"datePublished\":\"2020-02-05T06:19:22+00:00\",\"dateModified\":\"2024-12-31T11:00:28+00:00\",\"description\":\"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/02\\\/vca101.jpg\",\"contentUrl\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/02\\\/vca101.jpg\",\"width\":1069,\"height\":600,\"caption\":\"Lernplattform Via Cordis Akademie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lernplattform\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#website\",\"url\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\",\"name\":\"ViaCordis Akademie eLernen\",\"description\":\"Elektronisch unterst\u00fctztes Lernen - deutschsprachige Nutzer..\",\"publisher\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#organization\",\"name\":\"Via Cordis Akademie\",\"url\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/02\\\/vca-3.png\",\"contentUrl\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2020\\\/02\\\/vca-3.png\",\"width\":873,\"height\":443,\"caption\":\"Via Cordis Akademie\"},\"image\":{\"@id\":\"https:\\\/\\\/viacordis-akademie.de\\\/elernen\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lernplattform mit Herz und Verstand - ViaCordis Akademie","description":"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viacordis-akademie.de\/elernen\/","og_locale":"de_DE","og_type":"article","og_title":"Lernplattform mit Herz und Verstand - ViaCordis Akademie","og_description":"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...","og_url":"https:\/\/viacordis-akademie.de\/elernen\/","og_site_name":"ViaCordis Akademie eLernen","article_modified_time":"2024-12-31T11:00:28+00:00","og_image":[{"width":1069,"height":600,"url":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/viacordis-akademie.de\/elernen\/","url":"https:\/\/viacordis-akademie.de\/elernen\/","name":"Lernplattform mit Herz und Verstand - ViaCordis Akademie","isPartOf":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#primaryimage"},"image":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#primaryimage"},"thumbnailUrl":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101.jpg","datePublished":"2020-02-05T06:19:22+00:00","dateModified":"2024-12-31T11:00:28+00:00","description":"Lerne f\u00fcr deine Zukunft, meistere deine Berufung, deine Leidenschaft oder lerne einfach etwas Neues. Die Lernplattform f\u00fcr Online-Kurse...","breadcrumb":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viacordis-akademie.de\/elernen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/viacordis-akademie.de\/elernen\/#primaryimage","url":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101.jpg","contentUrl":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101.jpg","width":1069,"height":600,"caption":"Lernplattform Via Cordis Akademie"},{"@type":"BreadcrumbList","@id":"https:\/\/viacordis-akademie.de\/elernen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/viacordis-akademie.de\/elernen\/"},{"@type":"ListItem","position":2,"name":"Lernplattform"}]},{"@type":"WebSite","@id":"https:\/\/viacordis-akademie.de\/elernen\/#website","url":"https:\/\/viacordis-akademie.de\/elernen\/","name":"ViaCordis Akademie eLernen","description":"Elektronisch unterst\u00fctztes Lernen - deutschsprachige Nutzer..","publisher":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viacordis-akademie.de\/elernen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/viacordis-akademie.de\/elernen\/#organization","name":"Via Cordis Akademie","url":"https:\/\/viacordis-akademie.de\/elernen\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/viacordis-akademie.de\/elernen\/#\/schema\/logo\/image\/","url":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca-3.png","contentUrl":"https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca-3.png","width":873,"height":443,"caption":"Via Cordis Akademie"},"image":{"@id":"https:\/\/viacordis-akademie.de\/elernen\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/viacordis-akademie.de\/elernen\/wp-content\/uploads\/sites\/3\/2020\/02\/vca101-1024x575.jpg",1024,575,true],"author_info":{"display_name":"Zeljko","author_link":"https:\/\/viacordis-akademie.de\/elernen\/author\/redaktion\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/media\/66"}],"wp:attachment":[{"href":"https:\/\/viacordis-akademie.de\/elernen\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}